{"id":102940,"date":"2017-11-09T09:19:04","date_gmt":"2017-11-09T09:19:04","guid":{"rendered":"https:\/\/lavozdehellin.com\/noticias\/v01-519-la-portavoz-del-grupo-municipal-de-ciudadanos-en-hellin-ma-jesus-lopez-sometera-a-debate-de-pleno-una-iniciativa-para-favorecer-la-deteccion-y-atencion-de-menores-con-dislexia\/"},"modified":"2024-01-04T14:10:21","modified_gmt":"2024-01-04T14:10:21","slug":"v01-519-la-portavoz-del-grupo-municipal-de-ciudadanos-en-hellin-ma-jesus-lopez-sometera-a-debate-de-pleno-una-iniciativa-para-favorecer-la-deteccion-y-atencion-de-menores-con-dislexia","status":"publish","type":"post","link":"https:\/\/lavozdehellin.com\/noticias\/v01-519-la-portavoz-del-grupo-municipal-de-ciudadanos-en-hellin-ma-jesus-lopez-sometera-a-debate-de-pleno-una-iniciativa-para-favorecer-la-deteccion-y-atencion-de-menores-con-dislexia\/","title":{"rendered":"LVH NOTICIAS | LA PORTAVOZ DEL GRUPO MUNICIPAL DE CIUDADANOS EN HELL\u00cdN, M\u00aa JES\u00daS L\u00d3PEZ, SOMETER\u00c1 A DEBATE DE PLENO UNA INICIATIVA PARA FAVORECER LA DETECCI\u00d3N Y ATENCI\u00d3N DE MENORES CON DISLEXIA"},"content":{"rendered":"<p style=\"text-align: justify;\">La portavoz del grupo municipal de Ciudadanos en Hell\u00edn, M\u00aa Jes\u00fas L\u00f3pez, someter\u00e1 a debate de pleno una iniciativa para favorecer la detecci\u00f3n y atenci\u00f3n de menores con dislexia<\/p>\n<p><!--more--><br \/>\n<!--publicidad-voz01--><a href=\"https:\/\/www.facebook.com\/SoloRadioHellin\/?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEiNncirNnyGedv00mhjZjh5Wl4_YPdJGanoAl8tL8zH-HwqE8uHqjEfSt340RHdx-9tuCSIkZ8rFamZiGyYlgDGxCsmXjCH_1xk5eYM3ntFZRvJP_jndOKR7w1UAo9Tu0vrZyOLfqRpHIxYI5SymJJ-pfGCQw6QVpggBH-UgfjiFQ2JOxqxG0Jx94kW83c\/s1600\/logo-principal.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz01--><!--desk-in-out-voz01--><br \/>\n<!--publicidad-voz02--><a href=\"https:\/\/www.hellincf.com\/\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhuZ4-XfBVj3UtdP8-RZugy3WVrg-Zv28c53m4oV47qYCxL1rX_dqWX_YddsGSnpH5SRDqZ7bZeKPIfDVCDncpjVlhy3aQs2vojcJBn7Gdv9hC2_Nzct_pRFrnFE1a7KTCdY1bT_kAgnY3-iadRZrGeJf1fR2P5fu11bokx0pWjaypoy-ctwCjklldpEbA\/s1600\/logo-principal7.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz02--><!--desk-in-out-voz02--><\/p>\n<p style=\"text-align: justify;\">Coincidiendo con el D\u00eda Mundial de la Dislexia, el grupo municipal de Cs en el Ayuntamiento de Hell\u00edn ha registrado hoy una moci\u00f3n que \u201cpersigue mejorar la atenci\u00f3n que se presta a las personas que sufren esta Dificultad Espec\u00edfica de Aprendizaje. Una circunstancia que, seg\u00fan la Federaci\u00f3n Espa\u00f1ola de Dislexia y otras Dificultades Espec\u00edficas del Aprendizaje (FEDIS), tiene una incidencia del 15% en la poblaci\u00f3n espa\u00f1ola\u201d ha se\u00f1alado Mar\u00eda Jes\u00fas L\u00f3pez, portavoz de la formaci\u00f3n naranja.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, la edil de Cs ha explicado que \u201cinstamos a la JCCM a que elabore un plan multidisciplinar que afronte desde los \u00e1mbitos sanitario, educativo y social la inclusi\u00f3n de los menores afectados\u201d y ha a\u00f1adido que \u201cqueremos que se trabaje de forma coordinada entre las tres Consejer\u00edas con el objetivo de lograr una detecci\u00f3n y atenci\u00f3n adecuada a los menores con dislexia\u201d.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, la portavoz de Cs ha se\u00f1alado que \u201cactualmente, no se est\u00e1n haciendo las adaptaciones pertinentes que los reales decretos establecen para este colectivo. \u00a0No podemos olvidar que en Espa\u00f1a se estima que unos 700000 alumnos sufren dislexia\u201d.<\/p>\n<p style=\"text-align: justify;\">Finalmente, en la iniciativa propuesta por la informaci\u00f3n naranja se proponen, tambi\u00e9n, una serie de medidas para desarrollar en la localidad de Hell\u00edn, \u201cpedimos complementar la programaci\u00f3n l\u00fadica y cultural de nuestro municipio con actividades espec\u00edficamente adaptadas a personas con dislexia. As\u00ed como la elaboraci\u00f3n de un plan de ayudas a las familias que minimice cualquier barrera socioecon\u00f3mica de cara a la superaci\u00f3n de la dislexia por parte de los menores afectados; o \u00a0programar anualmente, en el marco del D\u00eda Mundial de la Dislexia, actos que permitan dar visibilidad a esta diversidad cognitiva favoreciendo con ello su inclusi\u00f3n\u201d ha concluido M\u00aa Jes\u00fas L\u00f3pez, portavoz de Cs.<\/p>\n<p><!--publicidad-voz03--><a href=\"https:\/\/www.facebook.com\/profile.php?id=100063593791305&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEi8_n_ll8UOcGxCqzFvb_9Io4ICczlGC990BPtPj2w9Px-u7B3oqWUW5vtjZUqPNJ-nyjiUIorE0ATsib_l5tV8BVN-UJ03RTnU__IHJF_4DgDBtY4LIqXNG-FomrO-7ywes20CBCRM2Hcm7EJSh3UUw1dO-c_uTflUrtgY1i7uBRezj_DpympmEFkfbQY\/s1600\/logo-principal2.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz03--><!--desk-in-out-voz03--><br \/>\n<!--publicidad-voz04--><a href=\"https:\/\/www.facebook.com\/profile.php?id=61557370768692&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgy5RdcfffrnrItnYTcV9bCJjgJwldsQLWssfVfrLbyfXeBNTFKgBf0rMIvhrUaGUhiXzVr9_eQgCbi-j63ZDpfTvLIty9w7s140y-m1yHe7eKmEK7v2NAHUJDVYGdfeiQFeRCqUjdwWmN1MX_AUxxz4IVdJ4WIM0APxit8bjWkXzrnEFGqBvW_1F13H1g\/s1600\/logo-principal5.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz04--><!--desk-in-out-voz04--><br \/>\n<!--publicidad-voz05--><a href=\"https:\/\/www.facebook.com\/asociaciontamborileroshellin?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhHEEpZsKK1VpwiYMrS7aE2ujtqIDZoLd4B5wtbiseSU9s2HdTdQfhF84So2XwEB1fv0BLw95GADm6hUl1bkKtzh-eIgVigXONuu_5RxeIMPhjk8q6uNX4EaEHbooKkbu7pCADWPpVJjhKIH5NQSJpWqedC-YBez4QAQeJYokkLot9bhrIaUAeztsGis6M\/s1600\/logo-principal3.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz05--><!--desk-in-out-voz05--><br \/>\n<!--publicidad-voz06--><!--bestpublic-voz06--><!--desk-in-out-voz06--><br \/>\n<!--publicidad-voz07--><!--bestpublic-voz07--><!--desk-in-out-voz07--><br \/>\n<!--publicidad-voz08--><!--bestpublic-voz08--><!--desk-in-out-voz08--><br \/>\n<!--publicidad-voz09--><!--bestpublic-voz09--><!--desk-in-out-voz09--><br \/>\n<!--publicidad-voz10--><!--bestpublic-voz10--><!--desk-in-out-voz10--><br \/>\n<!--publicidad-voz11--><!--bestpublic-voz11--><!--desk-in-out-voz11--><br \/>\n<!--publicidad-voz12--><!--bestpublic-voz12--><!--desk-in-out-voz12--><br \/>\n<!--publicidad-voz13--><!--bestpublic-voz13--><!--desk-in-out-voz13--><br \/>\n<!--publicidad-voz14--><!--bestpublic-voz14--><!--desk-in-out-voz14--><br \/>\n<!--publicidad-voz15--><!--bestpublic-voz15--><!--desk-in-out-voz15--><br \/>\n<!--publicidad-voz16--><!--bestpublic-voz16--><!--desk-in-out-voz16--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA PORTAVOZ DEL GRUPO MUNICIPAL DE CIUDADANOS EN HELL\u00cdN, M\u00aa JES\u00daS L\u00d3PEZ, SOMETER\u00c1 A DEBATE DE PLENO UNA INICIATIVA PARA FAVORECER LA DETECCI\u00d3N Y ATENCI\u00d3N DE MENORES CON DISLEXIA<\/p>\n","protected":false},"author":2,"featured_media":90583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[725,718,715,716,717],"tags":[],"class_list":["post-102940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-lv007","category-blogger","category-la-voz-de-hellin","category-la-voz-de-hellin-la-voz-de-hellin","category-noticias"],"_links":{"self":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/102940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/comments?post=102940"}],"version-history":[{"count":0,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/102940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media\/90583"}],"wp:attachment":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media?parent=102940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/categories?post=102940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/tags?post=102940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}