{"id":103071,"date":"2017-05-26T09:57:23","date_gmt":"2017-05-26T09:57:23","guid":{"rendered":"https:\/\/lavozdehellin.com\/noticias\/v01-650-el-gobierno-regional-apoya-a-la-familia-de-nieves-garcia-y-aplaude-la-aprobacion-de-la-pnl-de-derechos-humanos-de-presos-espanoles-en-el-extranjero\/"},"modified":"2024-01-04T14:10:41","modified_gmt":"2024-01-04T14:10:41","slug":"v01-650-el-gobierno-regional-apoya-a-la-familia-de-nieves-garcia-y-aplaude-la-aprobacion-de-la-pnl-de-derechos-humanos-de-presos-espanoles-en-el-extranjero","status":"publish","type":"post","link":"https:\/\/lavozdehellin.com\/noticias\/v01-650-el-gobierno-regional-apoya-a-la-familia-de-nieves-garcia-y-aplaude-la-aprobacion-de-la-pnl-de-derechos-humanos-de-presos-espanoles-en-el-extranjero\/","title":{"rendered":"LVH NOTICIAS | EL GOBIERNO REGIONAL APOYA A LA FAMILIA DE NIEVES GARC\u00cdA Y APLAUDE LA APROBACI\u00d3N DE LA PNL DE DERECHOS HUMANOS DE PRESOS ESPA\u00d1OLES EN EL EXTRANJERO."},"content":{"rendered":"<p style=\"text-align: justify;\">El Gobierno regional apoya a la familia de Nieves Garc\u00eda y aplaude la aprobaci\u00f3n de la PNL de derechos humanos de presos espa\u00f1oles en el extranjero.<\/p>\n<p><!--more--><br \/>\n<!--publicidad-voz01--><a href=\"https:\/\/www.facebook.com\/SoloRadioHellin\/?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEiNncirNnyGedv00mhjZjh5Wl4_YPdJGanoAl8tL8zH-HwqE8uHqjEfSt340RHdx-9tuCSIkZ8rFamZiGyYlgDGxCsmXjCH_1xk5eYM3ntFZRvJP_jndOKR7w1UAo9Tu0vrZyOLfqRpHIxYI5SymJJ-pfGCQw6QVpggBH-UgfjiFQ2JOxqxG0Jx94kW83c\/s1600\/logo-principal.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz01--><!--desk-in-out-voz01--><br \/>\n<!--publicidad-voz02--><a href=\"https:\/\/www.hellincf.com\/\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhuZ4-XfBVj3UtdP8-RZugy3WVrg-Zv28c53m4oV47qYCxL1rX_dqWX_YddsGSnpH5SRDqZ7bZeKPIfDVCDncpjVlhy3aQs2vojcJBn7Gdv9hC2_Nzct_pRFrnFE1a7KTCdY1bT_kAgnY3-iadRZrGeJf1fR2P5fu11bokx0pWjaypoy-ctwCjklldpEbA\/s1600\/logo-principal7.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz02--><!--desk-in-out-voz02--><\/p>\n<p style=\"text-align: justify;\">El presidente de la Asociaci\u00f3n +34, Javier Casado, y la hija de la tobarre\u00f1a Nieves Garc\u00eda, M\u00f3nica Soler, se han entrevistado con la consejera de Bienestar Social, Aurelia S\u00e1nchez, junto al director general de Coordinaci\u00f3n y Desarrollo, Alejandro Alonso, y el director general de Acci\u00f3n Social y Cooperaci\u00f3n, Ram\u00f3n Lara.<\/p>\n<p style=\"text-align: justify;\">La Proposici\u00f3n No de Ley (PNL), aprobada por aceptaci\u00f3n de todos los grupos, pide al Gobierno de Espa\u00f1a que lleve a cabo las acciones oportunas para garantizar los derechos de los ciudadanos espa\u00f1oles en c\u00e1rceles del extranjero.<\/p>\n<p style=\"text-align: justify;\">El Gobierno de Castilla-La Mancha ha expresado su apoyo a la familia de Nieves Garc\u00eda, natural de Tobarra (Albacete) que se encuentra encarcelada en Tailandia y se ha felicitado por la aprobaci\u00f3n por unanimidad de la Proposici\u00f3n No de Ley (PNL) sobre derechos humanos de los espa\u00f1oles en c\u00e1rceles extranjeras.<\/p>\n<p style=\"text-align: justify;\">As\u00ed lo ha manifestado la consejera de Bienestar Social, Aurelia S\u00e1nchez, que hoy se ha reunido con M\u00f3nica Soler, hija de la tobarre\u00f1a Nieves Garc\u00eda, y con el presidente de la Asociaci\u00f3n +34, Javier Casado, acompa\u00f1ada por el director general de Coordinaci\u00f3n y Planificaci\u00f3n del Gobierno de Castilla-La Mancha, Alejandro Alonso, y el director general de Acci\u00f3n Social y Cooperaci\u00f3n, Ram\u00f3n Lara.<\/p>\n<p style=\"text-align: justify;\">La consejera se ha interesado por el estado de salud de Nieves y ha conocido las gestiones que la Asociaci\u00f3n +34 realiza para defender los derechos humanos de los presos encarcelados en las c\u00e1rceles de otros pa\u00edses, que se cifran en 1.400, de los que 30 ser\u00edan castellano-manchegos.<\/p>\n<p style=\"text-align: justify;\">Contenido de la PNL<\/p>\n<p style=\"text-align: justify;\">El presidente de la Asociaci\u00f3n +34 ha expresado su satisfacci\u00f3n personal porque las Cortes de Castilla-La Mancha hayan expresado su apoyo un\u00e1nime a la PNL, que se muestra a favor de que el Gobierno de la naci\u00f3n \u201clleve a cabo las acciones oportunas para garantizar el respeto de los derechos humanos de las personas presas en las c\u00e1rceles extranjeras y el traslado en el marco de acuerdos bilaterales\u201d.<\/p>\n<p style=\"text-align: justify;\">En segundo lugar, la proposici\u00f3n dice que \u201cen caso de no existir dichos acuerdos, se realicen acuerdos diplom\u00e1ticos individualizados entre Espa\u00f1a y el Estado sobre cumplimiento de condena, para que puedan cumplir el resto de la condena en c\u00e1rceles de nuestro pa\u00eds y, preferentemente, dentro de nuestra Comunidad\u201d.<\/p>\n<p style=\"text-align: justify;\">Protocolo de colaboraci\u00f3n<\/p>\n<p style=\"text-align: justify;\">En su segundo punto, la PNL recoge que las Cortes de Castilla-La Mancha \u201cinstan al Consejo de Gobierno a aprobar un protocolo de colaboraci\u00f3n, con dotaci\u00f3n de fondos para actuaciones asistenciales, con las entidades sin \u00e1nimo de lucro que trabajan para garantizar los derechos y la calidad de vida de las personas castellano-manchegas en situaci\u00f3n de privaci\u00f3n de libertad en centros penitenciarios extranjeros\u201d.<\/p>\n<p style=\"text-align: justify;\">Finalmente recoge que \u201cpara el mejor cumplimiento de esta finalidad y evitar duplicidades en las actuaciones a estas personas, las Cortes de Castilla-La Mancha muestra su parecer favorable a la colaboraci\u00f3n de las entidades estatales que desarrollan similares programas, y en especial el Servicio Exterior del Estado, para obtener el mejor conocimiento de las situaciones personales a que se deben atender\u201d.<\/p>\n<p><!--publicidad-voz03--><a href=\"https:\/\/www.facebook.com\/profile.php?id=100063593791305&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEi8_n_ll8UOcGxCqzFvb_9Io4ICczlGC990BPtPj2w9Px-u7B3oqWUW5vtjZUqPNJ-nyjiUIorE0ATsib_l5tV8BVN-UJ03RTnU__IHJF_4DgDBtY4LIqXNG-FomrO-7ywes20CBCRM2Hcm7EJSh3UUw1dO-c_uTflUrtgY1i7uBRezj_DpympmEFkfbQY\/s1600\/logo-principal2.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz03--><!--desk-in-out-voz03--><br \/>\n<!--publicidad-voz04--><a href=\"https:\/\/www.facebook.com\/profile.php?id=61557370768692&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgy5RdcfffrnrItnYTcV9bCJjgJwldsQLWssfVfrLbyfXeBNTFKgBf0rMIvhrUaGUhiXzVr9_eQgCbi-j63ZDpfTvLIty9w7s140y-m1yHe7eKmEK7v2NAHUJDVYGdfeiQFeRCqUjdwWmN1MX_AUxxz4IVdJ4WIM0APxit8bjWkXzrnEFGqBvW_1F13H1g\/s1600\/logo-principal5.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz04--><!--desk-in-out-voz04--><br \/>\n<!--publicidad-voz05--><a href=\"https:\/\/www.facebook.com\/asociaciontamborileroshellin?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhHEEpZsKK1VpwiYMrS7aE2ujtqIDZoLd4B5wtbiseSU9s2HdTdQfhF84So2XwEB1fv0BLw95GADm6hUl1bkKtzh-eIgVigXONuu_5RxeIMPhjk8q6uNX4EaEHbooKkbu7pCADWPpVJjhKIH5NQSJpWqedC-YBez4QAQeJYokkLot9bhrIaUAeztsGis6M\/s1600\/logo-principal3.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz05--><!--desk-in-out-voz05--><br \/>\n<!--publicidad-voz06--><!--bestpublic-voz06--><!--desk-in-out-voz06--><br \/>\n<!--publicidad-voz07--><!--bestpublic-voz07--><!--desk-in-out-voz07--><br \/>\n<!--publicidad-voz08--><!--bestpublic-voz08--><!--desk-in-out-voz08--><br \/>\n<!--publicidad-voz09--><!--bestpublic-voz09--><!--desk-in-out-voz09--><br \/>\n<!--publicidad-voz10--><!--bestpublic-voz10--><!--desk-in-out-voz10--><br \/>\n<!--publicidad-voz11--><!--bestpublic-voz11--><!--desk-in-out-voz11--><br \/>\n<!--publicidad-voz12--><!--bestpublic-voz12--><!--desk-in-out-voz12--><br \/>\n<!--publicidad-voz13--><!--bestpublic-voz13--><!--desk-in-out-voz13--><br \/>\n<!--publicidad-voz14--><!--bestpublic-voz14--><!--desk-in-out-voz14--><br \/>\n<!--publicidad-voz15--><!--bestpublic-voz15--><!--desk-in-out-voz15--><br \/>\n<!--publicidad-voz16--><!--bestpublic-voz16--><!--desk-in-out-voz16--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL GOBIERNO REGIONAL APOYA A LA FAMILIA DE NIEVES GARC\u00cdA Y APLAUDE LA APROBACI\u00d3N DE LA PNL DE DERECHOS HUMANOS DE PRESOS ESPA\u00d1OLES EN EL EXTRANJERO.<\/p>\n","protected":false},"author":2,"featured_media":90579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[725,718,715,716,717],"tags":[],"class_list":["post-103071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-lv007","category-blogger","category-la-voz-de-hellin","category-la-voz-de-hellin-la-voz-de-hellin","category-noticias"],"_links":{"self":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/103071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/comments?post=103071"}],"version-history":[{"count":0,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/103071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media\/90579"}],"wp:attachment":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media?parent=103071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/categories?post=103071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/tags?post=103071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}