{"id":159575,"date":"2025-08-13T10:34:30","date_gmt":"2025-08-13T08:34:30","guid":{"rendered":"https:\/\/lavozdehellin.com\/noticias\/?p=159575"},"modified":"2025-08-25T09:12:01","modified_gmt":"2025-08-25T07:12:01","slug":"v10-235-lvh-noticias-la-diputacion-de-albacete-asiste-con-respaldo-juridico-y-tecnico-a-la-gineta-barrax-y-la-roda-contra-la-instalacion-del-vertedero-de-amianto","status":"publish","type":"post","link":"https:\/\/lavozdehellin.com\/noticias\/v10-235-lvh-noticias-la-diputacion-de-albacete-asiste-con-respaldo-juridico-y-tecnico-a-la-gineta-barrax-y-la-roda-contra-la-instalacion-del-vertedero-de-amianto\/","title":{"rendered":"LVH NOTICIAS | LA DIPUTACI\u00d3N DE ALBACETE ASISTE CON RESPALDO JUR\u00cdDICO Y T\u00c9CNICO A LA GINETA, BARRAX Y LA RODA CONTRA LA INSTALACI\u00d3N DEL VERTEDERO DE AMIANTO"},"content":{"rendered":"<p style=\"text-align: justify;\">El vicepresidente de la Diputaci\u00f3n de Albacete, Fran Valera, se ha reunido con el alcalde de La Gineta, Jos\u00e9 S\u00e1nchez; la alcaldesa de Barrax, Josefina Navarrete; y el concejal de Econom\u00eda y Hacienda de La Roda, Alberto Iglesias, para abordar la problem\u00e1tica derivada de la posible instalaci\u00f3n de un vertedero de amianto en el t\u00e9rmino municipal de Albacete, en un punto muy pr\u00f3ximo a estas tres localidades.<\/p>\n<p><!--more--><br \/>\n<!--publicidad-voz01--><a href=\"https:\/\/www.facebook.com\/SoloRadioHellin\/?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEiNncirNnyGedv00mhjZjh5Wl4_YPdJGanoAl8tL8zH-HwqE8uHqjEfSt340RHdx-9tuCSIkZ8rFamZiGyYlgDGxCsmXjCH_1xk5eYM3ntFZRvJP_jndOKR7w1UAo9Tu0vrZyOLfqRpHIxYI5SymJJ-pfGCQw6QVpggBH-UgfjiFQ2JOxqxG0Jx94kW83c\/s1600\/logo-principal.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz01--><!--desk-in-out-voz01--><br \/>\n<!--publicidad-voz02--><a href=\"https:\/\/www.hellincf.com\/\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhuZ4-XfBVj3UtdP8-RZugy3WVrg-Zv28c53m4oV47qYCxL1rX_dqWX_YddsGSnpH5SRDqZ7bZeKPIfDVCDncpjVlhy3aQs2vojcJBn7Gdv9hC2_Nzct_pRFrnFE1a7KTCdY1bT_kAgnY3-iadRZrGeJf1fR2P5fu11bokx0pWjaypoy-ctwCjklldpEbA\/s1600\/logo-principal7.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz02--><!--desk-in-out-voz02--><\/p>\n<p style=\"text-align: justify;\">La instituci\u00f3n provincial, que viene trabajando junto a los ayuntamientos afectados para defender sus intereses y los de sus vecinos y vecinas, ha elaborado a trav\u00e9s de su personal t\u00e9cnico un completo documento de alegaciones para oponerse a este proyecto. Incorporando las propuestas de todas las partes, este informe se ha puesto a disposici\u00f3n de La Gineta, Barrax y La Roda, reforzando el asesoramiento jur\u00eddico y t\u00e9cnico que la Diputaci\u00f3n les presta en todo momento.<\/p>\n<p style=\"text-align: justify;\">Valera ha explicado que el encuentro ha servido para analizar esas alegaciones, que alertan del gran impacto ambiental, social y en salud p\u00fablica que podr\u00eda tener la instalaci\u00f3n. \u201cSe trata de una planta de unas dimensiones importantes \u2014se estima que con 14 vasos de vertido, cada uno equivalente a un campo de f\u00fatbol\u2014 cuya ubicaci\u00f3n, pese a situarse administrativamente en Albacete capital, afecta de forma directa por cercan\u00eda a estos tres municipios\u201d, ha se\u00f1alado.<\/p>\n<p style=\"text-align: justify;\">En paralelo, el diputado provincial de Medio Ambiente, Jos\u00e9 Antonio G\u00f3mez, tambi\u00e9n se ha reunido estos d\u00edas con representantes de colectivos ciudadanos que vienen mostrando su preocupaci\u00f3n ante la posible instalaci\u00f3n del vertedero, traslad\u00e1ndoles G\u00f3mez la posici\u00f3n \u201crotundamente contraria\u201d del Gobierno Provincial as\u00ed como el respaldo total a las reivindicaciones vecinales.<\/p>\n<p style=\"text-align: justify;\">Principales argumentos contra el proyecto<\/p>\n<p style=\"text-align: justify;\">El documento de alegaciones preparado por la Diputaci\u00f3n detalla numerosos motivos por los que esta planta no deber\u00eda construirse. En primer lugar, advierte del grave riesgo ambiental que supondr\u00eda su ubicaci\u00f3n, ya que el lugar escogido se encuentra dentro de un espacio de gran valor para la biodiversidad, donde habitan especies de aves esteparias amenazadas. Tambi\u00e9n recuerda que el terreno est\u00e1 clasificado como de uso agr\u00edcola y que, seg\u00fan el planeamiento urban\u00edstico, no permite la instalaci\u00f3n de infraestructuras de residuos peligrosos.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, subraya que el principio de proximidad, que exige gestionar los residuos lo m\u00e1s cerca posible de donde se generan, no se cumplir\u00eda en este caso. La propia documentaci\u00f3n del promotor reconoce que llegar\u00edan restos de otras comunidades aut\u00f3nomas, incluyendo los de sectores que ni siquiera existen en la provincia, como pueden ser los de la industria naval o las centrales nucleares.<\/p>\n<p style=\"text-align: justify;\">A esto se suma el riesgo para la salud p\u00fablica y la seguridad vial, ya que el tr\u00e1fico de camiones cargados con amianto atravesar\u00eda zonas habitadas y carreteras locales, con el consiguiente peligro para la poblaci\u00f3n. El informe tambi\u00e9n pone de relieve la falta de informaci\u00f3n clara y precisa en el proyecto, se\u00f1alando importantes lagunas y contradicciones, as\u00ed como la ausencia de estudios completos sobre fauna, aguas subterr\u00e1neas, contaminaci\u00f3n del aire o gesti\u00f3n segura de los residuos.<\/p>\n<p style=\"text-align: justify;\">En definitiva, las conclusiones t\u00e9cnicas y jur\u00eddicas apuntan a que se trata de un proyecto con serias implicaciones para el medio ambiente, la salud y la calidad de vida de miles de personas, sin que exista una justificaci\u00f3n s\u00f3lida que avale su instalaci\u00f3n en la provincia.<\/p>\n<p style=\"text-align: justify;\">Defensa de los intereses de la provincia<\/p>\n<p style=\"text-align: justify;\">El vicepresidente de la Diputaci\u00f3n de Albacete ha reiterado que la instituci\u00f3n mantendr\u00e1 su apoyo institucional, t\u00e9cnico y jur\u00eddico a las localidades afectadas durante todo el procedimiento, con el objetivo de salvaguardar la salud, la seguridad y la calidad de vida de la ciudadan\u00eda, as\u00ed como de preservar los valores ambientales del territorio.<\/p>\n<p style=\"text-align: justify;\">Valera ha se\u00f1alado que el Gobierno Provincial est\u00e1 con los pueblos, defendiendo su derecho a decidir sobre proyectos que pueden condicionar su futuro y el del conjunto de la provincia, especialmente, en torno a casos como \u00e9ste donde la prudencia, la salud p\u00fablica y la protecci\u00f3n ambiental deben prevalecer sobre cualquier otro inter\u00e9s.<\/p>\n<p><!--publicidad-voz03--><a href=\"https:\/\/www.facebook.com\/profile.php?id=100063593791305&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEi8_n_ll8UOcGxCqzFvb_9Io4ICczlGC990BPtPj2w9Px-u7B3oqWUW5vtjZUqPNJ-nyjiUIorE0ATsib_l5tV8BVN-UJ03RTnU__IHJF_4DgDBtY4LIqXNG-FomrO-7ywes20CBCRM2Hcm7EJSh3UUw1dO-c_uTflUrtgY1i7uBRezj_DpympmEFkfbQY\/s1600\/logo-principal2.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz03--><!--desk-in-out-voz03--><br \/>\n<!--publicidad-voz04--><a href=\"https:\/\/www.facebook.com\/profile.php?id=61557370768692&amp;locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgy5RdcfffrnrItnYTcV9bCJjgJwldsQLWssfVfrLbyfXeBNTFKgBf0rMIvhrUaGUhiXzVr9_eQgCbi-j63ZDpfTvLIty9w7s140y-m1yHe7eKmEK7v2NAHUJDVYGdfeiQFeRCqUjdwWmN1MX_AUxxz4IVdJ4WIM0APxit8bjWkXzrnEFGqBvW_1F13H1g\/s1600\/logo-principal5.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz04--><!--desk-in-out-voz04--><br \/>\n<!--publicidad-voz05--><a href=\"https:\/\/www.facebook.com\/asociaciontamborileroshellin?locale=es_ES\"><img decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhHEEpZsKK1VpwiYMrS7aE2ujtqIDZoLd4B5wtbiseSU9s2HdTdQfhF84So2XwEB1fv0BLw95GADm6hUl1bkKtzh-eIgVigXONuu_5RxeIMPhjk8q6uNX4EaEHbooKkbu7pCADWPpVJjhKIH5NQSJpWqedC-YBez4QAQeJYokkLot9bhrIaUAeztsGis6M\/s1600\/logo-principal3.jpg\" width=\"100%\" height=\"100\" \/><\/a><!--bestpublic-voz05--><!--desk-in-out-voz05--><br \/>\n<!--publicidad-voz06--><!--bestpublic-voz06--><!--desk-in-out-voz06--><br \/>\n<!--publicidad-voz07--><!--bestpublic-voz07--><!--desk-in-out-voz07--><br \/>\n<!--publicidad-voz08--><!--bestpublic-voz08--><!--desk-in-out-voz08--><br \/>\n<!--publicidad-voz09--><!--bestpublic-voz09--><!--desk-in-out-voz09--><br \/>\n<!--publicidad-voz10--><!--bestpublic-voz10--><!--desk-in-out-voz10--><br \/>\n<!--publicidad-voz11--><!--bestpublic-voz11--><!--desk-in-out-voz11--><br \/>\n<!--publicidad-voz12--><!--bestpublic-voz12--><!--desk-in-out-voz12--><br \/>\n<!--publicidad-voz13--><!--bestpublic-voz13--><!--desk-in-out-voz13--><br \/>\n<!--publicidad-voz14--><!--bestpublic-voz14--><!--desk-in-out-voz14--><br \/>\n<!--publicidad-voz15--><!--bestpublic-voz15--><!--desk-in-out-voz15--><br \/>\n<!--publicidad-voz16--><!--bestpublic-voz16--><!--desk-in-out-voz16--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vicepresidente de la Diputaci\u00f3n de Albacete, Fran Valera, se ha reunido con el alcalde de La Gineta, Jos\u00e9 S\u00e1nchez; la alcaldesa de Barrax, Josefina Navarrete; y el concejal de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":159576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[760,718,715,716,717],"tags":[],"class_list":["post-159575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-lv041","category-blogger","category-la-voz-de-hellin","category-la-voz-de-hellin-la-voz-de-hellin","category-noticias"],"_links":{"self":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/159575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/comments?post=159575"}],"version-history":[{"count":0,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/posts\/159575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media\/159576"}],"wp:attachment":[{"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/media?parent=159575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/categories?post=159575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavozdehellin.com\/noticias\/wp-json\/wp\/v2\/tags?post=159575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}